{"id":175,"date":"2018-12-03T16:48:00","date_gmt":"2018-12-03T16:48:00","guid":{"rendered":"https:\/\/utegliwa.de\/?p=175"},"modified":"2020-04-30T16:53:12","modified_gmt":"2020-04-30T16:53:12","slug":"die-lust-der-anderen","status":"publish","type":"post","link":"https:\/\/utegliwa.de\/index.php\/2018\/12\/03\/die-lust-der-anderen\/","title":{"rendered":"Die Lust der Anderen"},"content":{"rendered":"\n<p>Neugier ist der Anfang allen Abenteuers. Wie es in einem Swingerclub wohl zugeht und ob da wirklich alle so viel hedonistischer und wilder sind als man selbst, haben sich sicher schon viele gefragt. Mein Mann und ich haben eine \u201eErotische Schlossnacht\u201c auf Schloss Milkersdorf besucht und es in Erfahrung gebracht.<\/p>\n\n\n\n<figure class=\"wp-block-image size-medium\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"200\" src=\"https:\/\/utegliwa.de\/wp-content\/uploads\/2020\/04\/GOE_4114-300x200.jpg\" alt=\"\" class=\"wp-image-176\" srcset=\"https:\/\/utegliwa.de\/wp-content\/uploads\/2020\/04\/GOE_4114-300x200.jpg 300w, https:\/\/utegliwa.de\/wp-content\/uploads\/2020\/04\/GOE_4114-768x513.jpg 768w, https:\/\/utegliwa.de\/wp-content\/uploads\/2020\/04\/GOE_4114.jpg 899w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/figure>\n\n\n\n<p>Wir fahren in den Spreewald. Diesmal\nallerdings nicht zum Paddeln. Mein Mann und ich sitzen heute allein\nim Auto, auf dem R\u00fccksitz nur ein paar Kleinigkeiten und am Fenster\nder B\u00fcgel mit unserer Abendgarderobe. Zuerst steuern wir das Dorf\nan, in dem unsere Unterkunft liegt. Das H\u00e4uschen ist gem\u00fctlich und\nliegt bildsch\u00f6n, es ist beinahe schade, dass wir kaum Zeit darin\nverbringen werden. W\u00e4hrend mein Mann duscht, werfe ich mich schon\nmal in Schale. Ein kritischer Moment. Ob wir es schaffen werden, das\nHaus zu verlassen? Wir hatten schon Schwierigkeiten, am Nachmittag\naus dem Bett zu kommen, in das wir vor \u00fcbereifriger Fantasie nach\nder Arbeit noch schnell springen mussten. Zum Gl\u00fcck haben wir das\nTaxi schon vor dem Umziehen bestellt, sodass wir nicht allzu\ndetailliert abschweifen k\u00f6nnen. \n<\/p>\n\n\n\n<p>Bei der Ankunft im Schloss sind wir\naufgeregt wie zwei gesch\u00fcttelte Brauseflaschen. Das Schloss,\neigentlich eher ein gediegenes Gutshaus, ist romantisch erleuchtet,\nneben der kleinen Freitreppe brennt ein Feuer. Vor uns steigt ein\nanderes Paar die Stufen hinauf. Er tr\u00e4gt einen hellgrauen Anzug, sie\nein kurzes Abendkleid unter dem Mantel. Sie k\u00f6nnten auch ins Theater\ngehen. W\u00e4hrend die beiden sich anmelden, haben wir kurz Zeit, uns im\nFoyer umzusehen. \u00dcberall h\u00e4ngen alte Bilder an der Wand, schwere\ndunkle M\u00f6bel und eiserne Kerzenst\u00e4nder stehen an den W\u00e4nden. Wir\nbekommen einen Schl\u00fcssel f\u00fcr das Schlie\u00dffach, in dem wir unsere\nJacken und Wertsachen einschlie\u00dfen k\u00f6nnen. Dann gibt es einen Sekt\nund, weil wir Erstbesucher sind, eine kleine Einf\u00fchrung. Ebenerdig\nbefinden sich zwei gro\u00dfe Hauptr\u00e4ume: das Kaminzimmer mit gr\u00fcnen\nW\u00e4nden und weinroten Ledersofas und der Raum mit dem Barbetrieb, in\ndem auch das Buffet steht und die G\u00e4ste speisen. F\u00fcr Raucher gibt\nes au\u00dferdem einen sich direkt am Hinterausgang anschlie\u00dfenden\nbeheizten Pavillon. Im Kaminzimmer wird paar- oder gr\u00fcppchenweise\nparliert, die meisten G\u00e4ste sitzen aber noch im Barraum an kleinen\nhohen Tischen und essen. Es l\u00e4uft ged\u00e4mpfte Lounge Musik, die G\u00e4ste\nsind elegant gekleidet. Bisher l\u00e4sst nichts den tieferen Zweck der\nVeranstaltung vermuten. Bis hierhin k\u00f6nnte man glatt seine Eltern\nmit hernehmen. \u201eDas ist aber h\u00fcbsch hier. Und endlich hat der\nJunge mal was Ordentliches an, nicht immer nur Jeans und Pullover.\u201c\n<\/p>\n\n\n\n<p>Wir setzen uns zu einem anderen Paar an\nden Tisch. Sie sind Mitte vierzig wie wir und extra quer durch\nDeutschland angereist, schon zum vierten Mal, wirken aber \u00fcberhaupt\nnicht wie Hedonisten. Im echten Leben haben sie Haus und Hof und zu\nviel Arbeit und kaum Zeit f\u00fcr sich selbst, klingt aus ihren\nErz\u00e4hlungen heraus. Mit so einem Abend g\u00f6nnen sie sich eben ab uns\nzu mal was Aufregendes. Mein Mann und ich gehen nach dem leckeren\nEssen und den ersten Drinks auf Entdeckungstour. Im flachen gew\u00f6lbten\nUntergeschoss liegen Sauna, Duschen und Whirlpool, flankiert von rot\nbezogenen Liegewiesen. Es ist noch niemand hier. Wir genie\u00dfen ein\npaar Momente lang unsere Zweisamkeit und teilen unter kichern und\nk\u00fcssen unsere ersten Eindr\u00fccke. Wir sind nicht wirklich darauf aus,\nmit anderen sexuell aktiv zu werden, wir wollen eher erstmal das\nAmbiente auf uns wirken lassen, zusehen was die anderen so treiben,\nund unter den Blicken der anderen zu zweit miteinander spielen. Wir\nhaben abgesprochen, an diesem Abend nicht mit anderen zu v\u00f6geln oder\nzu knutschen, aber anfassen oder anfassen lassen von Br\u00fcsten,\nHintern und Genitalien w\u00e4re okay, falls sich die Situation doch\nerg\u00e4be. F\u00fcr den Fall dass einer von uns etwas tut, das dem anderen\nunbehaglich ist, haben wir den Griff an den Ellbogen vereinbart. Dann\nmuss niemand sich oder dem anderen eine Bl\u00f6\u00dfe geben und die\nSituation kann diskret beendet werden. Wir gehen wieder hinauf ins\nKaminzimmer, das inzwischen voll ist. Alleine v\u00f6geln k\u00f6nnen wir ja\nauch zu Hause. Wir setzen uns auf einen gro\u00dfen Hocker vor dem Feuer\nund lassen unsere Sinnlichkeit von uns Besitz ergreifen. Wir sind\nnoch vom unvollendeten Nachmittag aufgeheizt, und der besondere Reiz\nder Situation liegt daran, dass alle um uns herum noch brav\nKonversation betreiben. Niemand au\u00dfer uns knutscht oder fummelt, das\neine oder andere Paar beobachtet uns aber, merken wir aus den\nAugenwinkeln. Da wir nicht wissen, ob weiterf\u00fchrende Aktivit\u00e4ten im\nErdgeschoss erw\u00fcnscht sind oder ob das Kaminzimmer ein\nunbescholtener R\u00fcckzugsort sein soll, gehen wir schlie\u00dflich hinauf\nin die Vergn\u00fcgungsetage. \n<\/p>\n\n\n\n<p>Der obere Raum, in den die Treppe\nm\u00fcndet, birgt diverse verschn\u00f6rkelte Sofas und Sessel, ein kurioses\nSexm\u00f6belst\u00fcck, das sich mir nicht sofort erschlie\u00dft und ein aus\ngrobem Holz gezimmertes Kreuz mit diversen Spielm\u00f6glichkeiten. Von\ndem Raum gehen diverse weitere ab, im ersten Moment meint man sich zu\nverlaufen, aber so kompliziert ist es dann doch nicht. Es gibt\nverschiedene R\u00e4ume oder Nischen mit rot bezogenen Spielwiesen, eine\nNacktsuite, einen Darkroom und einen mit Glory Holes, auch ein\nkleines abschlie\u00dfbares S\u00e9par\u00e9e f\u00fcr ganz ungest\u00f6rte Momente.\nDaneben gibt es F\u00e4cher zur Ablage von weiterer Kleidung und in jedem\nRaum liegen stapelweise Handt\u00fccher zum Unterlegen. Auch Kondome und\nGleitgelspender stehen an strategisch g\u00fcnstigen Punkten. Wir\nentscheiden uns f\u00fcr eine gro\u00dfe Polsterfl\u00e4che mit einem Spiegel\nschr\u00e4g an der Wand. Von unserer Position aus k\u00f6nnen wir au\u00dferdem\ndas Holzkreuz nebenan sehen. Ein etwas \u00fcppiges Paar in den 50ern hat\nsich daran eingerichtet. Ihre Augen sind verbunden, ihre H\u00e4nde oben\nam Kreuz fixiert. Breitbeinig steht sie in halterlosen Str\u00fcmpfen da\nund l\u00e4sst sich von ihrem Partner liebevoll den Po versohlen. W\u00e4hrend\nmein Mann und ich uns vergn\u00fcgen, h\u00f6ren wir seine Finger in ihrer\nM\u00f6se schmatzen, bis sie mit tiefem lustvollem St\u00f6hnen immer wieder\nabspritzt. Von etwas weiter weg h\u00f6ren wir eine Frau monoton st\u00f6hnen,\naber bei ihr klingt es eher nach inszeniertem Pornogest\u00f6hn. Vor\nunserer Liegefl\u00e4che bleiben immer wieder Menschen stehen und sehen\nuns zu, aber niemand legt sich zu uns oder fasst uns an, obwohl wir\nnichts dagegen h\u00e4tten. Wahrscheinlich sp\u00fcrt man, dass wir sehr\ninnig miteinander besch\u00e4ftigt sind. Aus den Augenwinkeln sehen wir\nmanchmal Leute vor\u00fcbergehen, wie sie unterschiedlicher nicht sein\nk\u00f6nnten. Manche wirken eher wie verirrte Museumsbesucher, manche\nsachlich als w\u00e4ren sie im B\u00fcro, nur eben komplett nackt. \n<\/p>\n\n\n\n<p>Nachdem wir \u2013 es stellt sich heraus\netliche Stunden sp\u00e4ter \u2013 wieder aus unserer Seifenblase\nauftauchen, uns ausruhen und Wasser trinken, das in Karaffen bereit\nsteht, wandern wir weiter durch die obere Etage und bleiben hier und\nda sitzen und gucken. Im Vorbeigehen fasst mir ein junger Mann kurz\nan die blo\u00dfen Br\u00fcste. Auf einem Sofa reitet eine kurzhaarige Frau\nauf einem Mann mit  h\u00fcbschem Schwanz. Er packt ihre Pobacken und\nzieht sie auseinander, sodass man seinen Schwanz in ihr verschwinden\nsehen kann. In einer Nische v\u00f6geln zwei nackte Paare nebeneinander,\ndas eine genussvoll langsam, das andere hektisch rammelnd. Sie\nwechseln ab und zu die Positionen, danach die Partner. Auf einer\ngro\u00dfen Fl\u00e4che liegen mehrere Paare wie Sardinen nebeneinander, aber\njedes scheint dennoch f\u00fcr sich. Auf einem runden Polster in der\nMitte des Raumes liegt eine Frau im Korsett und ein Mann hantiert an\nihren ausladenden Br\u00fcsten und in ihrem Schritt. Es ist ruhig\ngeworden, viele scheinen schon gegangen zu sein. \n<\/p>\n\n\n\n<p>Wir beschlie\u00dfen hinunter an die Bar zu\ngehen um noch einen Drink zu nehmen. Und stellen fest dass es zwei\nUhr ist. Ups. Sobald wir anfangen zu spielen, rast die Zeit. Wir\nkommen mit einem attraktiven \u00e4lteren Paar ins Gespr\u00e4ch. Sie sind\nseit drei\u00dfig Jahren verheiratet und seit zehn Jahren Swinger, kennen\nviele Clubs und Urlaubsorte zu diesem Zweck und erz\u00e4hlen uns von\nihren Anf\u00e4ngen und Erfahrungen seither. Auch sie sind schon oft aus\nS\u00fcddeutschland angereist, daf\u00fcr bleiben sie das ganze Wochenende\nund kommen am folgenden Abend nochmal ins Schloss. Mit unserem\nletzten Drink ziehen mein Mann und ich uns in den Au\u00dfenpavillon\nzur\u00fcck. Dort ist niemand mehr und die Luft ist angenehm frisch. Als\nwir nach kurzem Schmusen einer ersten kurzen Auswertung wieder\nhereinkommen, sind alle weg. Wir brauchen noch ein Taxi, sagen wir\ndem Barmann, der uns entgeistert anguckt. Es ist halb vier. Freitags\nschlie\u00dft das Schloss um drei. Immerhin d\u00fcrfen wir im Foyer warten,\ndenn drau\u00dfen ist es inzwischen empfindlich kalt und mein Kleid\nreicht nicht mal bis ganz \u00fcber den Po. W\u00e4hrend wir dort sitzen,\ntaucht noch ein Paar auf, das offenbar ebenso verspielt ist wie wir\nund die Zeit vergessen hat. Auch sie brauchen ein Taxi, in die\nentgegengesetzte Richtung. Die beiden sind jung, noch keine Drei\u00dfig,\nich habe sie vorher gar nicht bemerkt. Sie, blond, etwas drall, in\neinem kurzen roten Fransenkleid. Er, gro\u00df und schlank, mit\nHosentr\u00e4gern auf dem freien Oberk\u00f6rper und einem mehr als frechen\nFunkeln in den Augen. \u201eDer h\u00e4tte mir gefallen\u201c, raune ich meinem\nMann zu, tats\u00e4chlich der erste an diesem Abend. Wir gefallen den\nbeiden offenbar auch. Als unser Taxi eintrifft, h\u00e4lt mein Mann kurz\ninne. \u201eSollen wir sie mitnehmen?\u201c, raunt er mir zu. Ich z\u00f6gere,\ndann sch\u00fcttele ich den Kopf. Jetzt will ich lieber mit ihm allein\nsein, vor allem morgen fr\u00fch allein mit ihm aufwachen. \n<\/p>\n\n\n\n<p>Eigentlich sollten wir m\u00fcde sein, aber\ndie letzten paar Gin haben uns wieder angefeuert, und im Kopf\nschwirren unz\u00e4hlige neue Eindr\u00fccke und Fantasieszenarien herum, und\ndar\u00fcber hinaus f\u00e4llt die doch vorhandene Nervosit\u00e4t nun komplett\nvon uns ab. Nach dem ersten Ansturm ganz ungehemmter Lust fallen wir\nein paar Stunden in einen tiefen Schlaf, aber im Morgengrauen erwacht\nwie immer die Sinnlichkeit erneut mit uns und wir lieben uns,\nstreicheln, knutschen und fl\u00fcstern bis kurz vor Mittag. Wir schaffen\nes gerade noch kurz zu duschen und uns anzuziehen, bevor die\nPutzleute kommen und wir auschecken m\u00fcssen. \n<\/p>\n\n\n\n<p>Nach einem dringend notwendigen\nFr\u00fchst\u00fcck in Cottbus, das nur wenige Kilometer entfernt liegt,\nfahren wir zur\u00fcck nach Berlin. Am Nachmittag kommen die Kinder von\nden Gro\u00dfeltern zur\u00fcck.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Neugier ist der Anfang allen Abenteuers. Wie es in einem Swingerclub wohl zugeht und ob da wirklich alle so viel hedonistischer und wilder sind als man selbst, haben sich sicher schon viele gefragt. Mein Mann und ich haben eine \u201eErotische Schlossnacht\u201c auf Schloss Milkersdorf besucht und es in Erfahrung gebracht. Wir fahren in den Spreewald. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":177,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[],"class_list":["post-175","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-separee"],"_links":{"self":[{"href":"https:\/\/utegliwa.de\/index.php\/wp-json\/wp\/v2\/posts\/175","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/utegliwa.de\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/utegliwa.de\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/utegliwa.de\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/utegliwa.de\/index.php\/wp-json\/wp\/v2\/comments?post=175"}],"version-history":[{"count":1,"href":"https:\/\/utegliwa.de\/index.php\/wp-json\/wp\/v2\/posts\/175\/revisions"}],"predecessor-version":[{"id":178,"href":"https:\/\/utegliwa.de\/index.php\/wp-json\/wp\/v2\/posts\/175\/revisions\/178"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/utegliwa.de\/index.php\/wp-json\/wp\/v2\/media\/177"}],"wp:attachment":[{"href":"https:\/\/utegliwa.de\/index.php\/wp-json\/wp\/v2\/media?parent=175"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/utegliwa.de\/index.php\/wp-json\/wp\/v2\/categories?post=175"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/utegliwa.de\/index.php\/wp-json\/wp\/v2\/tags?post=175"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}